{"id":12498,"date":"2019-11-11T19:16:15","date_gmt":"2019-11-11T19:16:15","guid":{"rendered":"https:\/\/www.berneck-zwerenberg.de\/bz\/?p=12498"},"modified":"2019-11-11T19:16:17","modified_gmt":"2019-11-11T19:16:17","slug":"gerechte-punkteteilung-in-walddorf","status":"publish","type":"post","link":"https:\/\/www.berneck-zwerenberg.de\/bz\/gerechte-punkteteilung-in-walddorf\/","title":{"rendered":"Gerechte Punkteteilung in Walddorf"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Am vorletzten Spieltag in 2019 war man am vergangenen Sonntag zu Gast in Walddorf.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In einem sehr ausgeglichenen Spiel bekam unsere SG fr\u00fch einen Elfmeter zu gesprochen. Aus diesem schwach geschossenen Elfmeter von Spielf\u00fchrer Daniel Axnix konnte man aber nichts z\u00e4hlbares heraus holen. Der Torwart der Gastgeber hatte diesen relativ einfach entsch\u00e4rft.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Danach pl\u00e4tscherte das Spiel so vor dich hin. Es gab auf beiden Seiten mal mehr, mal weniger grosse Chancen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erst in der 67. Minute wurde es etwas hitziger. Rico Hoffmann musste nach einem Ausrutscher bei dem er den Gegner traf mit gelb-rot vom Platz. Zumindest die gelbe Karte aus der ersten Halbzeit war hier strittig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die letzten 20 Minuten Spielte man nun in Unterzahl.<br>Obwohl man etwas mehr vereidigen musste, konnte Walddorf nur selten gute Chancen erspielen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Unentschieden konnte so noch gut \u00fcber die Zeit gebracht werden. Nach dem 2:7 vom Hinspiel ist das mehr als ein Achtungserfolg.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zuvor spielten noch die Reserven.<br>Nach dem 0:14 In der Hinrunde war auch hier Wiedergutmachung angesagt. Unsere SG hatte die besseren und mehr Torchancen, musste sich aber dennoch kurz vor Schluss noch nach einer 2:1 F\u00fchrung mit 2:3 geschlagen geben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der n\u00e4chsten Woche findet das letzte Spiel in diesem Jahr zu Hause in Spielberg gegen \u00dcberberg statt. Die Reserven spielen um 12.30Uhr und die aktiven um 14.30Uhr.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Geschrieben von Patrick Wurster <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am vorletzten Spieltag in 2019 war man am vergangenen Sonntag zu Gast in Walddorf. In einem sehr ausgeglichenen Spiel bekam unsere SG fr\u00fch einen Elfmeter zu gesprochen. Aus diesem schwach geschossenen Elfmeter von Spielf\u00fchrer Daniel Axnix konnte man aber nichts z\u00e4hlbares heraus holen. Der Torwart der Gastgeber hatte diesen relativ einfach entsch\u00e4rft. Danach pl\u00e4tscherte das&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/www.berneck-zwerenberg.de\/bz\/gerechte-punkteteilung-in-walddorf\/\" class=\"excerpt-read-more\">Weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":6854,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[135,1,63],"tags":[],"class_list":["post-12498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-herren-reserve","category-allgemein","category-herren"],"publishpress_future_action":{"enabled":false,"date":"2029-09-02 15:41:52","action":"change-status","newStatus":"private","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.berneck-zwerenberg.de\/bz\/wp-json\/wp\/v2\/posts\/12498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.berneck-zwerenberg.de\/bz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.berneck-zwerenberg.de\/bz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.berneck-zwerenberg.de\/bz\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.berneck-zwerenberg.de\/bz\/wp-json\/wp\/v2\/comments?post=12498"}],"version-history":[{"count":1,"href":"https:\/\/www.berneck-zwerenberg.de\/bz\/wp-json\/wp\/v2\/posts\/12498\/revisions"}],"predecessor-version":[{"id":12499,"href":"https:\/\/www.berneck-zwerenberg.de\/bz\/wp-json\/wp\/v2\/posts\/12498\/revisions\/12499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.berneck-zwerenberg.de\/bz\/wp-json\/wp\/v2\/media\/6854"}],"wp:attachment":[{"href":"https:\/\/www.berneck-zwerenberg.de\/bz\/wp-json\/wp\/v2\/media?parent=12498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.berneck-zwerenberg.de\/bz\/wp-json\/wp\/v2\/categories?post=12498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.berneck-zwerenberg.de\/bz\/wp-json\/wp\/v2\/tags?post=12498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}